{"id":962,"date":"2019-07-08T14:03:25","date_gmt":"2019-07-08T12:03:25","guid":{"rendered":"https:\/\/toleranciacero.org.es\/web\/?p=962"},"modified":"2019-07-08T14:03:25","modified_gmt":"2019-07-08T12:03:25","slug":"es-seguro-beber-una-copa-de-vino-al-dia-despues-del-segundo-trimestre-de-gestacion","status":"publish","type":"post","link":"https:\/\/toleranciacero.org.es\/web\/es-seguro-beber-una-copa-de-vino-al-dia-despues-del-segundo-trimestre-de-gestacion\/","title":{"rendered":"\u00bfES SEGURO BEBER UNA COPA DE VINO AL D\u00cdA DESPU\u00c9S DEL SEGUNDO TRIMESTRE DE GESTACI\u00d3N?"},"content":{"rendered":"<p>En un\u00a0<a href=\"https:\/\/elpais.com\/elpais\/2019\/07\/04\/eps\/1562249434_291416.html\">art\u00edculo<\/a> publicado ayer en El Pa\u00eds Semanal se menciona un dato sobre la inocuidad del consumo de una copa de vino al d\u00eda a partir del segundo trimestre de gestaci\u00f3n, que ha suscitado una gran alarma en expertos y asociaciones de familias afectadas por el Trastorno del Espectro Alcoh\u00f3lico Fetal, a la que nos sumamos desde Tolerancia Cero.<\/p>\n<p>Seg\u00fan la Organizaci\u00f3n Mundial de la Salud, un consumo espor\u00e1dico de alcohol, como una o dos bebidas a la semana y que no signifique m\u00e1s de 20-30 gramos de etanol al d\u00eda, no tiene clara su inocuidad, de ah\u00ed que desde el organismo internacional se recomiende consumo cero de alcohol durante la gestaci\u00f3n. En cambio, en el art\u00edculo se asegura que una copa de vino diario es un consumo inocuo.<\/p>\n<p>La afirmaci\u00f3n de Emily Oster en su libro \u201cExpecting Better\u201d y que se menciona en el art\u00edculo, contradice los criterios de la OMS, seg\u00fan los cuales podr\u00eda provocar en el feto d\u00e9ficit cognitivo leve, alteraci\u00f3n del comportamiento o alteraci\u00f3n del crecimiento. Por lo tanto no se tratar\u00eda de un consumo seguro, como ella afirma.<\/p>\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-963 size-full\" src=\"https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.54.39.png\" alt=\"\" width=\"870\" height=\"588\" srcset=\"https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.54.39.png 870w, https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.54.39-300x203.png 300w, https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.54.39-768x519.png 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/h1>\n<p>Es cierto que esto no ocurre en todos los casos porque hay otros factores en juego que podr\u00edan influir en la vulnerabilidad de un feto a los efectos teratog\u00e9nicos del alcohol, como la variabilidad en los antecedentes metab\u00f3licos y gen\u00e9ticos tanto de la madre como del feto, las influencias medioambientales, el tabaquismo materno, el estado nutricional, los niveles de estr\u00e9s, y posiblemente el estilo de vida paterno. Ante esta incertidumbre lo aconsejable es el consumo cero, ya que no se ha podido establecer una cantidad m\u00ednima que no suponga riesgo. Decir lo contrario, como hace Emily Oster, y refleja el art\u00edculo de El Pa\u00eds Semanal, es jugar a la ruleta rusa con el futuro del beb\u00e9 en gestaci\u00f3n.<\/p>\n<p>Oster plantea que a partir del segundo trimestre no hay peligro. Veamos que ocurre en ese periodo y hasta el momento del parto.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-965 size-full\" src=\"https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.58.43.png\" alt=\"\" width=\"772\" height=\"520\" srcset=\"https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.58.43.png 772w, https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.58.43-300x202.png 300w, https:\/\/toleranciacero.org.es\/web\/wp-content\/uploads\/2019\/07\/Captura-de-pantalla-2019-07-08-a-las-12.58.43-768x517.png 768w\" sizes=\"auto, (max-width: 772px) 100vw, 772px\" \/><\/p>\n<p>Cada parte del cuerpo del futuro beb\u00e9 se forma en un cierto momento del embarazo. Durante ese tiempo, ese \u00f3rgano o esa parte del cuerpo, es especialmente sensible al da\u00f1o causado por cualquier sustancia t\u00f3xica. Ese momento se denomina \u201cper\u00edodo cr\u00edtico para el desarrollo\u201d de esa parte del cuerpo. Una vez que esa parte se ha formado no hay riesgo de desarrollar grandes malformaciones cong\u00e9nitas, pero todav\u00eda hay riesgo de que pueda afectar a su crecimiento y a su funci\u00f3n.<\/p>\n<p>Las barras rosas del cuadro muestran cuando cada parte es m\u00e1s sensible a las exposiciones da\u00f1inas y al riesgo de importantes malformaciones cong\u00e9nitas. Se clasifican como \u201cmayores\u201d si causan problemas m\u00e9dicos significativos y necesitan la cirug\u00eda u otro tratamiento para reparar. Defectos card\u00edacos, espina b\u00edfida y malformaciones cong\u00e9nitas de los pies son ejemplos de defectos \u201cmayores\u201d.<\/p>\n<p>Las barras verdes muestran cuando las partes del cuerpo tienen riesgo de desarrollar malformaciones cong\u00e9nitas menores y defectos funcionales.<\/p>\n<p>Las malformaciones cong\u00e9nitas mayores y menores provocan cambios f\u00edsicos, estructurales. Sin embargo, en el caso de los defectos \u201cfuncionales\u201d no cambia su estructura f\u00edsica pero s\u00ed su funcionamiento.\u00a0La discapacidad intelectual es un claro ejemplo de defecto funcional que puede ocurrir tambi\u00e9n a lo largo del tercer trimestre como consecuencia del \u201cconsumo social\u201d del que habla Emily Oster.\u00a0Es decir, no hay ninguna cantidad m\u00ednima de consumo de alcohol que se pueda considerar segura en el embarazo.<\/p>\n<p>Muchas mujeres reducen o suprimen el consumo de alcohol durante la gestaci\u00f3n, pero se estima que entre un 25%-50% de las mujeres embarazadas en la Uni\u00f3n Europea contin\u00faan consumiendo durante este periodo. En Espa\u00f1a, un estudio reciente indica que el 40,7% de mujeres embarazadas toma alcohol el primer mes de gestaci\u00f3n y el 17,1% sigue tomando alcohol los tres \u00faltimos meses.<\/p>\n<p>Seg\u00fan algunos c\u00e1lculos el S\u00edndrome Alcoh\u00f3lico Fetal (SAF), que es la secuela m\u00e1s grave del consumo de alcohol durante el embarazo puede afectar a 2 de cada 1.000 reci\u00e9n nacidos vivos en Espa\u00f1a, pero los Trastornos del Espectro Alcoh\u00f3lico Fetal (TEAF), la afectaci\u00f3n m\u00e1s leve del trastorno, que cursa con s\u00edntomas de d\u00e9ficit de atenci\u00f3n, dificultades de aprendizaje, hiperactividad \u00a0y alteraciones del comportamiento, que suele estar asociado a fracaso escolar e inicio precoz del consumo excesivo de alcohol, pueden afectar a una poblaci\u00f3n 10 veces mayor.<\/p>\n<p>Por tanto, no se trata de un problema de unos pocos, sino de la sociedad en general. El S\u00edndrome Alcoh\u00f3lico Fetal, que es la secuela m\u00e1s grave del consumo de alcohol durante el embarazo se ha convertido en la Uni\u00f3n Europea en la segunda causa de discapacidad intelectual y de trastornos del neurodesarrollo tras el s\u00edndrome de Down, siendo la \u00fanica causa cien por cien evitable.<\/p>\n<p>El consumo de alcohol por mujeres ha ido en aumento a la par que el desarrollo econ\u00f3mico y los cambios en los roles de g\u00e9nero, pero tambi\u00e9n a causa de otros factores como la publicidad dirigida a las mujeres, el aumento de la disponibilidad y accesibilidad de las bebidas alcoh\u00f3licas y el incremento de la aceptabilidad social del consumo de alcohol por mujeres. En Espa\u00f1a, seg\u00fan las estad\u00edsticas, las mujeres que m\u00e1s alcohol consumen son aquellas que tienen estudios superiores.<\/p>\n<p>Es decir, no hay ninguna cantidad m\u00ednima de consumo de alcohol que se pueda considerar segura en el embarazo, por lo que la afirmaci\u00f3n de Emily Oster, reproducida en el art\u00edculo, puede suponer un grave riesgo para el beb\u00e9. Es especialmente grave que no se contraste dicha opini\u00f3n con las recomendaciones de organismos oficiales como \u00a0la Organizaci\u00f3n Mundial de la Salud, en cuanto a que el consumo cero es la \u00fanica medida segura para el feto.<\/p>\n<p>\u00bfHasta qu\u00e9 punto la informaci\u00f3n que ofrece un medio de comunicaci\u00f3n se debe ofrecer sin ning\u00fan tipo de contraste, especialmente cuando esa desinformaci\u00f3n puede provocar un trastorno que no tiene cura y cuyas secuelas son de por vida?<\/p>\n<p>Marga Mu\u00f1iz Aguilar<\/p>\n<p>Presidenta de Tolerancia Cero<\/p>\n<p>marga@toleranciacero.org.es<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un\u00a0art\u00edculo publicado ayer en El Pa\u00eds Semanal se menciona un dato sobre la inocuidad del consumo de una copa de vino al d\u00eda a partir del segundo trimestre de gestaci\u00f3n, que ha suscitado una gran alarma en expertos y asociaciones de familias afectadas por el Trastorno del Espectro Alcoh\u00f3lico Fetal, a la que nos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[71,21,31],"class_list":["post-962","post","type-post","status-publish","format-standard","hentry","category-blog","tag-embarazo-y-alcohol","tag-saf","tag-teaf"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9arT9-fw","jetpack-related-posts":[{"id":844,"url":"https:\/\/toleranciacero.org.es\/web\/video-de-la-primera-sesion-de-las-ii-jornadas-virtuales-de-teaf\/","url_meta":{"origin":962,"position":0},"title":"V\u00cdDEO DE LA PRIMERA SESI\u00d3N DE LAS II JORNADAS VIRTUALES DE TEAF","author":"Tolerancia cero","date":"23\/11\/2018","format":false,"excerpt":"Ayer, d\u00eda 22 de Noviembre se celebr\u00f3 la primera sesi\u00f3n de las II Jornadas Virtuales de TEAF. Fue una sesi\u00f3n muy interesante, ilustrativa y did\u00e1ctica sobre los criterios diagn\u00f3sticos y las valoraciones neuropsicol\u00f3gicas de aquellos menores, adolescentes y j\u00f3venes que sufrieron durante su gestaci\u00f3n los efectos del consumo de alcohol.\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/toleranciacero.org.es\/web\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2018\/11\/Captura-de-pantalla-2018-11-18-a-las-21.11.34.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1691,"url":"https:\/\/toleranciacero.org.es\/web\/dia-mundial-del-teaf-5\/","url_meta":{"origin":962,"position":1},"title":"D\u00cdA MUNDIAL DEL TEAF","author":"Tolerancia cero","date":"09\/09\/2024","format":false,"excerpt":"Desde 1999, cada 9 de septiembre se celebra el d\u00eda mundial del Trastorno del Espectro Alcoh\u00f3lico Fetal. Se celebra el d\u00eda 9 del 9 por los nueve meses de embarazo. El objetivo es de dar a conocer las consecuencias del consumo de alcohol durante el embarazo y las necesidades de\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/toleranciacero.org.es\/web\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2017\/07\/image4173.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2017\/07\/image4173.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2017\/07\/image4173.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2017\/07\/image4173.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2017\/07\/image4173.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2017\/07\/image4173.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":740,"url":"https:\/\/toleranciacero.org.es\/web\/conocimientos-de-los-profesionales-de-la-salud-sobre-el-consumo-de-alcohol-durante-el-embarazo\/","url_meta":{"origin":962,"position":2},"title":"CONOCIMIENTOS DE LOS PROFESIONALES DE LA SALUD SOBRE LOS RIESGOS DEL CONSUMO DE ALCOHOL DURANTE EL EMBARAZO","author":"Tolerancia cero","date":"02\/07\/2018","format":false,"excerpt":"Las evidencias, tanto cl\u00ednicas como experimentales, sobre el efecto terat\u00f3geno del etanol contenido en las bebidas alcoh\u00f3licas, es hoy en d\u00eda incuestionable. Desde 1973 est\u00e1n descritas las secuelas que provocan en el feto en formaci\u00f3n cuando se consume alcohol durante el embarazo. Sin embargo, estas evidencias contrastan con el desconocimiento\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/toleranciacero.org.es\/web\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2018\/07\/Captura-de-pantalla-2018-07-02-a-las-21.40.28-300x206.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":345,"url":"https:\/\/toleranciacero.org.es\/web\/dia-internacional-del-saf\/","url_meta":{"origin":962,"position":3},"title":"D\u00eda Internacional del SAF","author":"Tolerancia Cero","date":"07\/09\/2017","format":false,"excerpt":"Desde 1999, cada 9 de septiembre se celebra el d\u00eda mundial del S\u00edndrome Alcoh\u00f3lico Fetal. Se celebra el d\u00eda 9 del 9 por los nueve meses de embarazo. El objetivo es de dar a conocer las consecuencias del consumo de alcohol durante el embarazo y las necesidades de los ni\u00f1os,\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/toleranciacero.org.es\/web\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2017\/09\/Captura-de-pantalla-2017-09-08-a-las-12.32.17.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1417,"url":"https:\/\/toleranciacero.org.es\/web\/dia-mundial-del-teaf-3\/","url_meta":{"origin":962,"position":4},"title":"D\u00eda Mundial del TEAF","author":"Tolerancia cero","date":"09\/09\/2022","format":false,"excerpt":"Desde 1999, cada 9 de septiembre se celebra el d\u00eda mundial del S\u00edndrome Alcoh\u00f3lico Fetal. Se celebra el d\u00eda 9 del 9 por los nueve meses de embarazo. El objetivo es de dar a conocer las consecuencias del consumo de alcohol durante el embarazo y las necesidades de los ni\u00f1os,\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/toleranciacero.org.es\/web\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2022\/09\/1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2022\/09\/1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2022\/09\/1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2022\/09\/1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2022\/09\/1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2022\/09\/1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1542,"url":"https:\/\/toleranciacero.org.es\/web\/dia-mundial-del-teaf-4\/","url_meta":{"origin":962,"position":5},"title":"D\u00cdA MUNDIAL DEL TEAF","author":"Tolerancia cero","date":"08\/09\/2023","format":false,"excerpt":"Desde 1999, cada 9 de septiembre se celebra el d\u00eda mundial del S\u00edndrome Alcoh\u00f3lico Fetal. Se celebra el d\u00eda 9 del 9 por los nueve meses de embarazo. El objetivo es de dar a conocer las consecuencias del consumo de alcohol durante el embarazo y las necesidades de los ni\u00f1os,\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/toleranciacero.org.es\/web\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2023\/09\/FLYER-DIA-MUNDIAL-DEL-TEAF.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2023\/09\/FLYER-DIA-MUNDIAL-DEL-TEAF.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2023\/09\/FLYER-DIA-MUNDIAL-DEL-TEAF.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/toleranciacero.org.es\/web\/wp-content\/uploads\/2023\/09\/FLYER-DIA-MUNDIAL-DEL-TEAF.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":11,"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"predecessor-version":[{"id":975,"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/posts\/962\/revisions\/975"}],"wp:attachment":[{"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toleranciacero.org.es\/web\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}